{"id":80,"count":0,"description":"","link":"https:\/\/effetquebec.ca\/en\/products_services_technologies\/motion-design\/","name":"Motion design","slug":"motion-design","taxonomy":"produits_services_technologies","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motion design Archives - Effet Qu\u00e9bec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/effetquebec.ca\/en\/products_services_technologies\/motion-design\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motion design Archives - Effet Qu\u00e9bec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/effetquebec.ca\/en\/products_services_technologies\/motion-design\/\" \/>\n<meta property=\"og:site_name\" content=\"Effet Qu\u00e9bec\" \/>\n<meta property=\"og:image\" content=\"https:\/\/effetquebec.ca\/wp-content\/uploads\/2021\/10\/800x400.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/products_services_technologies\\\/motion-design\\\/\",\"url\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/products_services_technologies\\\/motion-design\\\/\",\"name\":\"Motion design Archives - Effet Qu\u00e9bec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/products_services_technologies\\\/motion-design\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/products_services_technologies\\\/motion-design\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motion design\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/\",\"name\":\"Effet Qu\u00e9bec\",\"description\":\"P\u00f4le d\u2019expertise en exportation\",\"publisher\":{\"@id\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/#organization\",\"name\":\"L\u2019Effet Qu\u00e9bec\",\"url\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/effetquebec.ca\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/EffetQuebec.LogoVertical.RGB_.Noir-fav-1.png\",\"contentUrl\":\"https:\\\/\\\/effetquebec.ca\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/EffetQuebec.LogoVertical.RGB_.Noir-fav-1.png\",\"width\":512,\"height\":512,\"caption\":\"L\u2019Effet Qu\u00e9bec\"},\"image\":{\"@id\":\"https:\\\/\\\/effetquebec.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/XnQuebec\",\"https:\\\/\\\/www.instagram.com\\\/xnquebec\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/xnquebec\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motion design Archives - Effet Qu\u00e9bec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/effetquebec.ca\/en\/products_services_technologies\/motion-design\/","og_locale":"en_US","og_type":"article","og_title":"Motion design Archives - Effet Qu\u00e9bec","og_url":"https:\/\/effetquebec.ca\/en\/products_services_technologies\/motion-design\/","og_site_name":"Effet Qu\u00e9bec","og_image":[{"width":800,"height":400,"url":"https:\/\/effetquebec.ca\/wp-content\/uploads\/2021\/10\/800x400.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/effetquebec.ca\/en\/products_services_technologies\/motion-design\/","url":"https:\/\/effetquebec.ca\/en\/products_services_technologies\/motion-design\/","name":"Motion design Archives - Effet Qu\u00e9bec","isPartOf":{"@id":"https:\/\/effetquebec.ca\/en\/#website"},"breadcrumb":{"@id":"https:\/\/effetquebec.ca\/en\/products_services_technologies\/motion-design\/#breadcrumb"},"inLanguage":"en-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/effetquebec.ca\/en\/products_services_technologies\/motion-design\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/effetquebec.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Motion design"}]},{"@type":"WebSite","@id":"https:\/\/effetquebec.ca\/en\/#website","url":"https:\/\/effetquebec.ca\/en\/","name":"Effet Qu\u00e9bec","description":"P\u00f4le d\u2019expertise en exportation","publisher":{"@id":"https:\/\/effetquebec.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/effetquebec.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/effetquebec.ca\/en\/#organization","name":"L\u2019Effet Qu\u00e9bec","url":"https:\/\/effetquebec.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/effetquebec.ca\/en\/#\/schema\/logo\/image\/","url":"https:\/\/effetquebec.ca\/wp-content\/uploads\/2026\/04\/EffetQuebec.LogoVertical.RGB_.Noir-fav-1.png","contentUrl":"https:\/\/effetquebec.ca\/wp-content\/uploads\/2026\/04\/EffetQuebec.LogoVertical.RGB_.Noir-fav-1.png","width":512,"height":512,"caption":"L\u2019Effet Qu\u00e9bec"},"image":{"@id":"https:\/\/effetquebec.ca\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/XnQuebec","https:\/\/www.instagram.com\/xnquebec\/","https:\/\/www.linkedin.com\/company\/xnquebec\/"]}]}},"_links":{"self":[{"href":"https:\/\/effetquebec.ca\/en\/wp-json\/wp\/v2\/produits_services_technologies\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/effetquebec.ca\/en\/wp-json\/wp\/v2\/produits_services_technologies"}],"about":[{"href":"https:\/\/effetquebec.ca\/en\/wp-json\/wp\/v2\/taxonomies\/produits_services_technologies"}],"wp:post_type":[{"href":"https:\/\/effetquebec.ca\/en\/wp-json\/wp\/v2\/entreprises?produits_services_technologies=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}